{"id":203,"count":7,"description":"","link":"https:\/\/sawabona-africa.com\/de\/category\/bildungslandschaft\/","name":"Bildungslandschaft","slug":"bildungslandschaft","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bildungslandschaft - Sawabona Africa e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sawabona-africa.com\/category\/educational-landscape\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bildungslandschaft - Sawabona Africa e.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sawabona-africa.com\/category\/educational-landscape\/\" \/>\n<meta property=\"og:site_name\" content=\"Sawabona Africa e.V.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sawabona-africa.com\/wp-content\/uploads\/2023\/04\/option2-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bildungslandschaft - Sawabona Africa e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sawabona-africa.com\/category\/educational-landscape\/","og_locale":"de_DE","og_type":"article","og_title":"Bildungslandschaft - Sawabona Africa e.V.","og_url":"https:\/\/sawabona-africa.com\/category\/educational-landscape\/","og_site_name":"Sawabona Africa e.V.","og_image":[{"width":1600,"height":1067,"url":"https:\/\/sawabona-africa.com\/wp-content\/uploads\/2023\/04\/option2-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sawabona-africa.com\/category\/educational-landscape\/","url":"https:\/\/sawabona-africa.com\/category\/educational-landscape\/","name":"Bildungslandschaft - Sawabona Africa e.V.","isPartOf":{"@id":"https:\/\/sawabona-africa.com\/#website"},"breadcrumb":{"@id":"https:\/\/sawabona-africa.com\/category\/educational-landscape\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/sawabona-africa.com\/category\/educational-landscape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sawabona-africa.com\/de\/"},{"@type":"ListItem","position":2,"name":"Educational Landscape"}]},{"@type":"WebSite","@id":"https:\/\/sawabona-africa.com\/#website","url":"https:\/\/sawabona-africa.com\/","name":"Sawabona Africa","description":"Support Education. Deliver Hope.","publisher":{"@id":"https:\/\/sawabona-africa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sawabona-africa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sawabona-africa.com\/#organization","name":"Sawabona Africa e.V.","url":"https:\/\/sawabona-africa.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sawabona-africa.com\/#\/schema\/logo\/image\/","url":"https:\/\/sawabona-africa.com\/wp-content\/uploads\/2021\/01\/logo_sawabona-africa_final.png","contentUrl":"https:\/\/sawabona-africa.com\/wp-content\/uploads\/2021\/01\/logo_sawabona-africa_final.png","width":779,"height":324,"caption":"Sawabona Africa e.V."},"image":{"@id":"https:\/\/sawabona-africa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SawabonaAfrica","https:\/\/www.instagram.com\/sawabonaafrica\/","https:\/\/www.linkedin.com\/company\/sawabona-africa\/","https:\/\/www.linkedin.com\/company\/sawabona-africa-de\/"]}]}},"_links":{"self":[{"href":"https:\/\/sawabona-africa.com\/de\/wp-json\/wp\/v2\/categories\/203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sawabona-africa.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sawabona-africa.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sawabona-africa.com\/de\/wp-json\/wp\/v2\/posts?categories=203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}